{"id":32881,"date":"2026-04-21T16:51:56","date_gmt":"2026-04-21T23:51:56","guid":{"rendered":"https:\/\/peninsula360press.com\/?p=32881"},"modified":"2026-04-21T16:51:56","modified_gmt":"2026-04-21T23:51:56","slug":"gobierno-mexicano-galardona-a-investigadora-de-videojuegos","status":"publish","type":"post","link":"https:\/\/peninsula360press.com\/en\/gobierno-mexicano-galardona-a-investigadora-de-videojuegos\/","title":{"rendered":"Gobierno Mexicano galardona a investigadora de videojuegos por dos d\u00e9cadas de trayectoria"},"content":{"rendered":"<p>El Congreso de la Ciudad de M\u00e9xico entreg\u00f3 este 21 de abril la Medalla al M\u00e9rito en las Artes a nueve mexicanos y mexicanas destacados, entre ellos, se encuentra la Dra. Ruth Sof\u00eda Contreras, quien ha dedicado dos d\u00e9cadas a la investigaci\u00f3n de videojuegos.<\/p>\n<p>Esta medalla reconoce la trayectoria de la doctora que consolida la intersecci\u00f3n entre dise\u00f1o y cultura digital, as\u00ed como su contribuci\u00f3n al fortalecimiento de comunidades profesionales entre M\u00e9xico y Catalu\u00f1a.<\/p>\n<figure id=\"attachment_32883\" aria-describedby=\"caption-attachment-32883\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-32883\" src=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-21-at-11.06.58-AM-300x225.webp\" alt=\"Dra. Ruth Sof\u00eda Contreras en la ceremonia de entrega de la Medalla al M\u00e9rito en las Artes. Foto: Cortes\u00eda. \" width=\"683\" height=\"512\" srcset=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-21-at-11.06.58-AM-300x225.webp 300w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-21-at-11.06.58-AM-1024x768.webp 1024w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-21-at-11.06.58-AM-768x576.webp 768w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-21-at-11.06.58-AM-16x12.webp 16w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-21-at-11.06.58-AM-150x113.webp 150w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-21-at-11.06.58-AM-696x522.webp 696w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-21-at-11.06.58-AM-1068x801.webp 1068w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption id=\"caption-attachment-32883\" class=\"wp-caption-text\">Dra. Ruth Sof\u00eda Contreras en la ceremonia de entrega de la Medalla al M\u00e9rito en las Artes. Foto: Cortes\u00eda.<\/figcaption><\/figure>\n<p>En entrevista con Mexican Press Agency (MxPA), la Dra. Ruth Contreras,\u00a0 destac\u00f3 la importancia de la investigaci\u00f3n en el \u00e1rea de los videojuegos: \u201cEs importante estudiar videojuegos porque son un medio de cultura, de comunicaci\u00f3n y es un medio que nos sirve para el aprendizaje\u201d.<\/p>\n<p>La investigadora lamenta la estigmatizaci\u00f3n del tema y lo menciona como una barrera para ampliar la discusi\u00f3n sobre el tema. \u201cSimplemente por el hecho de jugar un juego uno no se hace lud\u00f3pata ni violento\u201d, coment\u00f3 a MxPA.<\/p>\n<p>La Dra. Ruth tambi\u00e9n se\u00f1al\u00f3 la importancia de los videojuegos para mostrar la cultura de cada pa\u00eds. En el caso de M\u00e9xico, mencion\u00f3 el videojuego Pancito Merge, que celebra la tradici\u00f3n panadera mexicana e invita a todo el mundo a conocer m\u00e1s de la cultura mexicana a partir de sus gastronom\u00eda.<\/p>\n<p>\u201cEn el caso de M\u00e9xico se pueden ver cada vez m\u00e1s obras creadas por desarrolladores los cuales llegan a demostrar la riqueza cultural que tiene el pa\u00eds\u201d, coment\u00f3.<\/p>\n<p>La Dra. Ruth Sof\u00eda Contreras tambi\u00e9n ha recibido un reconocimiento de la Secretar\u00eda de Relaciones Exteriores en el 2020 por su trayectoria sobresaliente en el extranjero. Con 25 a\u00f1os en Espa\u00f1a, ha logrado estrechar los lazos entre ambas naciones y destacar el talento de los mexicanos.<\/p>\n<p>La investigadora tambi\u00e9n celebr\u00f3 el cambio en la percepci\u00f3n sobre los mexicanos que ha sucedido en dos d\u00e9cadas: \u201cel estereotipo (del mexicano) era el de el sombrero con el zarape, flojo. Ahora no, esa visi\u00f3n ha cambiado. Incluso nos ven como gente muy ambiciosa, ha sido trabajo de muchos que hemos migrado.. Sabemos ser profesionales, sabemos ser l\u00edderes. Los mexicanos en cualquier lado podemos destacar si nos lo proponemos\u201d.<\/p>\n<p>La destacada mexicana hizo un llamado a las instituciones mexicanas a seguir el ejemplo de otros pa\u00edses y apoyar a la industria nacional de videojuegos con incentivos fiscales. Tambi\u00e9n mencion\u00f3 la necesidad de una mejor organizaci\u00f3n para apoyos y trabajo conjunto por parte del gobierno mexicano con los desarrolladores de videojuegos.<\/p>\n<p>\u201cLamentablemente, lo que est\u00e1 pasando ahora, y lo que est\u00e1 pasando en Europa es que much\u00edsimos mexicanos, que son muy valiosos en el \u00e1rea de los videojuegos, est\u00e1n migrando y se est\u00e1n yendo a empresas grandes que est\u00e1n ah\u00ed. Se est\u00e1 perdiendo un valor impresionante que se podr\u00eda aprovechar aqu\u00ed mismo si se dan esas ayudas, si se dan estos incentivos\u201d, puntualiz\u00f3 la investigadora.<\/p>\n<p>La Dra. Ruth Contreras, junto con la Dra. Blanca L\u00f3pez, presiden DIGRA Mx, una asociaci\u00f3n de investigaci\u00f3n de videojuegos en M\u00e9xico que es parte de un organismo internacional con el mismo prop\u00f3sito: ser un punto de encuentro para investigadores, acad\u00e9micos, estudiantes y profesionales de los videojuegos para fomentar la colaboraci\u00f3n a nivel internacional.<\/p>\n<p>Con este merecido reconocimiento, la destacada mexicana redobla esfuerzos que se materializan en M\u00e9xico en el <a href=\"https:\/\/digramx.org\/es\/el-nuevo-umoma-abre-sus-puertas-2\" target=\"_blank\" rel=\"noopener\">4to Congreso Internacional Digra Mx 2026<\/a> con el t\u00edtulo de Simulaci\u00f3n, Juegos y Sociedad digital que se llevar\u00e1 a cabo del 29 de junio al 3 de julio en la Ciudad de M\u00e9xico.<\/p>\n<p><strong><em>You may also be interested in:\u00a0<a href=\"https:\/\/peninsula360press.com\/en\/mexicana-pionera-en-la-composicion-de-musica-para-videojuegos-jimena-contreras\/\" target=\"_blank\" rel=\"noopener\">Mexicana pionera en la composici\u00f3n de m\u00fasica para videojuegos: Jimena Contreras<\/a><\/em><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>El Congreso de la Ciudad de M\u00e9xico entreg\u00f3 este 21 de abril la Medalla al M\u00e9rito en las Artes a nueve mexicanos y mexicanas destacados, entre ellos, se encuentra la Dra. Ruth Sof\u00eda Contreras, quien ha dedicado dos d\u00e9cadas a la investigaci\u00f3n de videojuegos. Esta medalla reconoce la trayectoria de la doctora que consolida la [&hellip;]<\/p>","protected":false},"author":20,"featured_media":32882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":{"0":"post-32881","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-culture"},"_links":{"self":[{"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/posts\/32881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/comments?post=32881"}],"version-history":[{"count":2,"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/posts\/32881\/revisions"}],"predecessor-version":[{"id":32997,"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/posts\/32881\/revisions\/32997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/media\/32882"}],"wp:attachment":[{"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/media?parent=32881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/categories?post=32881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/peninsula360press.com\/en\/wp-json\/wp\/v2\/tags?post=32881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}