{"id":21097,"date":"2023-12-05T11:38:42","date_gmt":"2023-12-05T18:38:42","guid":{"rendered":"https:\/\/peninsula360press.com\/?p=21097"},"modified":"2023-12-05T11:38:42","modified_gmt":"2023-12-05T18:38:42","slug":"era-del-cambio-climatico","status":"publish","type":"post","link":"https:\/\/peninsula360press.com\/es_mx\/era-del-cambio-climatico\/","title":{"rendered":"Productores org\u00e1nicos ven un nuevo papel en la era del cambio clim\u00e1tico"},"content":{"rendered":"<figure id=\"attachment_21099\" aria-describedby=\"caption-attachment-21099\" style=\"width: 1600px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-21099 size-full\" src=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5.jpeg\" alt=\"Productores org\u00e1nicos ven un nuevo papel en la era del cambio clim\u00e1tico\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5.jpeg 1600w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5-300x225.jpeg 300w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5-1024x768.jpeg 1024w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5-768x576.jpeg 768w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5-16x12.jpeg 16w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5-150x113.jpeg 150w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5-696x522.jpeg 696w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-5-1068x801.jpeg 1068w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-21099\" class=\"wp-caption-text\">Tierras de cultivo labradas alrededor de la ciudad de Castroville en el condado de Monterey. 30 de noviembre de 2023 (Ruth Dusseault \/ Bay City News)<\/figcaption><\/figure>\n<p><strong>Por Ruth Dusseault. <a href=\"https:\/\/www.baycitynews.com\/\" target=\"_blank\" rel=\"noopener\">Bay City News<\/a>.<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Curiosamente, es dif\u00edcil encontrar un trabajo que luche en la era del cambio clim\u00e1tico. Pero la industria de la agricultura org\u00e1nica es un lugar donde una persona puede ganarse la vida marcando la diferencia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los sistemas alimentarios representan entre 20 y 30 por ciento de las emisiones mundiales de gases de efecto invernadero, seg\u00fan datos del Banco Mundial. La reinvenci\u00f3n de la agricultura podr\u00eda impactar el futuro tanto como el coche el\u00e9ctrico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En la Cumbre de Productores Org\u00e1nicos de la semana pasada, organizada por Western Growers y Organic Produce Network, m\u00e1s de 600 productores y l\u00edderes de la industria, en su mayor\u00eda de California, se reunieron en Monterey para compartir problemas, soluciones y tarjetas de presentaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los grandes temas incluyeron nuevas tecnolog\u00edas y nuevas regulaciones gubernamentales que podr\u00edan aumentar los costos. Detr\u00e1s de casi todas las discusiones estuvo la salud regenerativa del suelo y su potencial para combatir enfermedades, repeler plagas y capturar carbono.<\/span><\/p>\n<figure id=\"attachment_21100\" aria-describedby=\"caption-attachment-21100\" style=\"width: 1600px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-21100 size-full\" src=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1.jpeg\" alt=\"Productores org\u00e1nicos ven un nuevo papel en la era del cambio clim\u00e1tico\" width=\"1600\" height=\"896\" srcset=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1.jpeg 1600w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1-300x168.jpeg 300w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1-1024x573.jpeg 1024w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1-768x430.jpeg 768w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1-18x10.jpeg 18w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1-150x84.jpeg 150w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1-696x390.jpeg 696w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-1-1068x598.jpeg 1068w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-21100\" class=\"wp-caption-text\">En la Cumbre de Productores Org\u00e1nicos 2023, Monterey, CA, Bart Walker, Paul Mikesell, Tom Nunes y Kristin Smith Eshaya discuten los obst\u00e1culos y oportunidades de la tecnolog\u00eda en la agricultura org\u00e1nica, 30 de noviembre de 2023 (Ruth Dusseault \/ Bay City News)<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">California lidera el pa\u00eds en agricultura org\u00e1nica, con m\u00e1s de 3 mil granjas certificadas, seg\u00fan cifras de 2022 del Departamento de Agricultura de los Estados Unidos o USDA. En 2021, las ventas org\u00e1nicas del estado superaron los 14 mil millones de d\u00f3lares. Eso es el equivalente a 43 d\u00f3lares por persona en EE. UU. que compra productos org\u00e1nicos. S\u00f3lo en la regi\u00f3n del \u00c1rea de la Bah\u00eda, que abarca desde los condados de Monterey hasta Sonoma, hay m\u00e1s de mil 550 productores org\u00e1nicos que generan casi mil 400 millones de d\u00f3lares en ventas brutas anuales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gradualmente, los agricultores m\u00e1s convencionales est\u00e1n adoptando productos org\u00e1nicos y algunos transforman sus tierras de cultivo multigeneracionales. Aportan experiencia empresarial, innovaciones y capital a lo que alguna vez fue una econom\u00eda de nicho.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Estoy en esto por el dinero&#8221;, dijo Carlos Amaral, un productor del condado de San Mateo, quien refiri\u00f3 que est\u00e1 dispuesto a afrontar el mayor costo de producci\u00f3n porque el comprador est\u00e1 dispuesto a pagar m\u00e1s a cambio. Los compradores m\u00e1s j\u00f3venes de hoy, afirm\u00f3, son m\u00e1s conscientes del medio ambiente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero para marzo de 2024, los precios org\u00e1nicos podr\u00edan aumentar a medida que entren en vigencia las nuevas reglas del USDA para la certificaci\u00f3n org\u00e1nica. La norma de Fortalecimiento de la Aplicaci\u00f3n Org\u00e1nica (SOE, por sus siglas en ingl\u00e9s) establecer\u00e1 nuevos est\u00e1ndares para todos los involucrados en la producci\u00f3n. Todos los eslabones de la cadena de suministro (cultivadores, distribuidores, transportistas e importadores) necesitar\u00e1n estar certificados org\u00e1nicamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Est\u00e1s verificando que entienden c\u00f3mo mantener las cosas org\u00e1nicas&#8221;, dijo Danny Lee, inspector del Departamento de Alimentaci\u00f3n y Agricultura de California. &#8220;Estar\u00e1 seguro de que no mezclan productos org\u00e1nicos con productos no org\u00e1nicos, que pueden tener diferentes pesticidas u otros insumos&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Va a ser m\u00e1s caro, se\u00f1al\u00f3, pero que se transmita depende de qui\u00e9n est\u00e9 dispuesto a absorber esos costos y de lo que los minoristas finales est\u00e9n dispuestos a pagar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La cumbre se centr\u00f3 en los desaf\u00edos \u00fanicos de los cultivos especiales, como verduras de hojas verdes, bayas y zanahorias. Son diferentes de los cultivos b\u00e1sicos, como el ma\u00edz y la soya, que se cultivan a gran escala utilizando semillas resistentes a herbicidas y m\u00e9todos de cosecha industriales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los cultivos especiales necesitan mucha mano de obra intensa y los herbicidas sint\u00e9ticos como Roundup no est\u00e1n permitidos en granjas certificadas org\u00e1nicamente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Lo que veo que tenemos sobresaturado es el mercado del deshierbe&#8221;, destac\u00f3 Bart Walker, que dirige una empresa de alquiler de equipos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Walker se refer\u00eda a la variedad de escardadoras mec\u00e1nicas que se exhiben en la cumbre. En lugar de pedir a los trabajadores que hagan el agotador trabajo de arrancar la maleza a mano, los ingenieros han dise\u00f1ado una variedad de m\u00e1quinas para hacerlo. Tiradas por un tractor, paletas, cuchillas y p\u00faas giratorias alteran el suelo entre las hileras de cultivos e impiden que las malas hierbas echen ra\u00edces.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Lo que me emociona ver es m\u00e1s l\u00e1seres&#8221;, dijo Walker.<\/span><\/p>\n<figure id=\"attachment_21098\" aria-describedby=\"caption-attachment-21098\" style=\"width: 1600px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-21098 size-full\" src=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4.jpeg\" alt=\"Productores org\u00e1nicos ven un nuevo papel en la era del cambio clim\u00e1tico\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4.jpeg 1600w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4-300x225.jpeg 300w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4-1024x768.jpeg 1024w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4-768x576.jpeg 768w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4-16x12.jpeg 16w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4-150x113.jpeg 150w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4-696x522.jpeg 696w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-4-1068x801.jpeg 1068w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-21098\" class=\"wp-caption-text\">Desmalezador rob\u00f3tico que no utiliza herbicidas en la Cumbre de Productores Org\u00e1nicos, Monterey, CA, 29 de noviembre de 2023 (Ruth Dusseault \/ Bay City News)<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">&#8220;Resulta que hacer que la gente camine por el campo y arranque las malas hierbas con azadas y herramientas da\u00f1ar\u00e1 parte de la estructura de la planta&#8221;, dijo Paul Mikesell, inventor del LaserWeeder de Carbon Robotics. &#8220;Cuando la maleza es lo suficientemente alta como para que una persona pueda arrancarla, la estructura de la ra\u00edz es lo suficientemente profunda como para alterar tambi\u00e9n las ra\u00edces de los cultivos&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">LaserWeeder utiliza inteligencia artificial para identificar las malas hierbas cuando apenas son brotes. Con un coste de 1.4 millones de d\u00f3lares, utiliza fotograf\u00edas con flash para crear miles de im\u00e1genes de alta resoluci\u00f3n del suelo mientras se arrastra por un campo. Las computadoras a bordo interpretan la informaci\u00f3n de la imagen y la env\u00edan a espejos rob\u00f3ticos en la parte trasera de la m\u00e1quina, que giran para dirigir un rayo l\u00e1ser. Las malas hierbas son eliminadas en una nube de humo.<\/span><\/p>\n<figure id=\"attachment_21102\" aria-describedby=\"caption-attachment-21102\" style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21102 size-full\" src=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3.jpeg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3.jpeg 1600w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3-300x225.jpeg 300w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3-1024x768.jpeg 1024w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3-768x576.jpeg 768w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3-16x12.jpeg 16w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3-150x113.jpeg 150w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3-696x522.jpeg 696w, https:\/\/peninsula360press.com\/wp-content\/uploads\/2023\/12\/Productores-organicos-3-1068x801.jpeg 1068w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-21102\" class=\"wp-caption-text\">En la Cumbre de Productores Org\u00e1nicos de 2023 en Monterey, CA, Carbon Robotics demostr\u00f3 su Laserweeder. La m\u00e1quina utiliza inteligencia artificial para fotografiar e identificar reto\u00f1os de malezas y luego los quema con un l\u00e1ser dirigido rob\u00f3ticamente. 30 de noviembre de 2023 (Ruth Dusseault \/ Bay City News)<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">&#8220;No da\u00f1a la capa superior del suelo, no da\u00f1a el ecosistema y tambi\u00e9n es bueno para el medio ambiente&#8221;, dijo Mikesell.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante siglos, los agricultores araron los campos entre estaciones, pero ahora se les dice que usen un toque tierno. Exponer la capa superior del suelo al aire libera carbono atrapado. La luz del sol quema nutrientes importantes y hongos buenos que los agricultores org\u00e1nicos utilizan para combatir plagas y enfermedades. La captura de carbono es una nueva funci\u00f3n para los agricultores, como lo demuestran dos premios presentados en la cumbre: un premio al innovador Ag Shark y un premio al Productor del A\u00f1o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Jason Aramburu es el fundador de Climate Robotics e inventor de un peque\u00f1o incinerador m\u00f3vil de biocarb\u00f3n. Imag\u00ednese un horno de alfarer\u00eda sobre ruedas. Puede moverse por una planta procesadora o arrastrarse detr\u00e1s de un tractor. Digiere desechos, como tallos de ma\u00edz, trigo, paja y c\u00e1scaras de nueces, y deposita biocarb\u00f3n all\u00ed mismo, en el suelo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;El biocarb\u00f3n es una forma muy pura de carb\u00f3n vegetal elaborado a partir de desechos agr\u00edcolas que quemamos a una temperatura muy alta y aplicamos nuevamente al suelo&#8221;, dijo Aramburu al recibir su premio de inversi\u00f3n Ag Shark. Cit\u00f3 estudios universitarios que demostraron que el biocarb\u00f3n puede generar 16 por ciento m\u00e1s de producci\u00f3n vegetal en comparaci\u00f3n con los campos sin biocarb\u00f3n. Ha aumentado la retenci\u00f3n de agua del suelo en 51 por ciento y la retenci\u00f3n de fertilizantes en 95 por ciento, dijo.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Si hacemos esto a una escala suficientemente grande, los estudios indican que podemos secuestrar alrededor de 2 mil millones de toneladas de CO2 anualmente en los suelos de nuestras granjas&#8221;, explic\u00f3 Aramburu.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El USDA ofrece alrededor de dos mil d\u00f3lares por acre por temporada a los productores que apliquen biocarb\u00f3n a su suelo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;La agricultura es considerada la segunda industria productora de CO2, justo detr\u00e1s de los combustibles f\u00f3siles&#8221;, afirm\u00f3 Rod Braga, de Braga Fresh Farms, al aceptar el premio al Productor Org\u00e1nico del A\u00f1o.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Las presiones realmente vienen de arriba hacia abajo&#8221;, se\u00f1al\u00f3 sobre la presi\u00f3n para que la agricultura adopte medidas de conservaci\u00f3n. &#8220;No me refiero a los minoristas. Me refiero a las Naciones Unidas, el Foro Econ\u00f3mico Mundial, la Uni\u00f3n Europea&#8221;.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Braga habl\u00f3 de las formas en que la agricultura ha tratado de ser neutra en carbono: utilizando menos combustible di\u00e9sel, plantando un cultivo sobre otro en lugar de labrarlo e invirtiendo en el secuestro de carbono en otros lugares para compensar el carbono generado en las granjas locales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Ahora est\u00e1n hablando de cero emisiones netas&#8221;, dijo refiri\u00e9ndose a la teor\u00eda de una econom\u00eda que no emite m\u00e1s gases de efecto invernadero de los que se eliminan y almacenan permanentemente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;\u00bfC\u00f3mo podemos llegar a cero en la agricultura sin cortar cultivos y matar de hambre a millones? Podemos capturar carbono mientras cultivamos&#8221;, dijo Braga. &#8220;Todav\u00eda estamos cultivando hortalizas y otros cultivos. Necesitamos ser la respuesta. M\u00e1s acres agr\u00edcolas es lo que necesitaremos en el mundo y no menos&#8221;.<\/span><\/p>\n<p><em><strong>Te puede interesar:<\/strong> <a href=\"https:\/\/peninsula360press.com\/es_mx\/como-nos-cambia-el-cambio-climatico\/\">C\u00f3mo nos cambia el cambio clim\u00e1tico<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Ruth Dusseault. Bay City News. Curiosamente, es dif\u00edcil encontrar un trabajo que luche en la era del cambio clim\u00e1tico. Pero la industria de la agricultura org\u00e1nica es un lugar donde una persona puede ganarse la vida marcando la diferencia. Los sistemas alimentarios representan entre 20 y 30 por ciento de las emisiones mundiales de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,6],"tags":[],"class_list":{"0":"post-21097","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cover","8":"category-habitat"},"_links":{"self":[{"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/posts\/21097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/comments?post=21097"}],"version-history":[{"count":1,"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/posts\/21097\/revisions"}],"predecessor-version":[{"id":21103,"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/posts\/21097\/revisions\/21103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/media\/21099"}],"wp:attachment":[{"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/media?parent=21097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/categories?post=21097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/peninsula360press.com\/es_mx\/wp-json\/wp\/v2\/tags?post=21097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}